{"id":3972,"date":"2020-11-11T08:34:56","date_gmt":"2020-11-11T08:34:56","guid":{"rendered":"http:\/\/onlineclassesguru.com\/?p=3972"},"modified":"2020-11-11T08:34:56","modified_gmt":"2020-11-11T08:34:56","slug":"vocabulario","status":"publish","type":"post","link":"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/","title":{"rendered":"VOCABULARIO"},"content":{"rendered":"<style type=\"text\/css\"><\/style><p>VOCABULARIO? Write the letter of the sentence in column B that is most logically related to each question or statement in column A. (10 pts.) A 1. __________ \u00bfD\u00f3nde est\u00e1 la tienda? 2. __________ \u00bfQu\u00e9 talla usa Ud.? 3. __________ La tienda est\u00e1 de rebajas. 4. __________ Tengo fr\u00edo en las manos. 5. __________ Voy a la playa. 6. __________ Llueve. 7. __________ \u00bfQu\u00e9 n\u00famero calza? 8. __________ \u00bfDonde est\u00e1 mi tarjeta de cr\u00e9dito? 9. __________ Es amarillo. 10. __________Los pantalones son demasiado largos.<\/p>\n<p>B a. Todo est\u00e1 muy barato. b. Ese color no me gusta. c. En la cartera. d. \u00bfTiene unos m\u00e1s cortos? e. Necesito un impermeable. f. La peque\u00f1a. g. En el centro comercial. h. Necesita unos guantes. i. Necesitas un traje de ba\u00f1o. j. El treinta y siete.<\/p>\n<p>M\u00c1S VOCABULARIO? Answer the questions with the correct vocabulary words. 10 pts.) 1. \u00bfQu\u00e9 es lo opuesto de (?the opposite of?) largo? ____________________ 2. \u00bfQu\u00e9 es lo opuesto de nuevo? ____________________ 3. \u00bfQu\u00e9 es lo opuesto de grande? ____________________ 4. \u00bfQu\u00e9 es lo opuesto de rico? ____________________ 5. \u00bfQu\u00e9 es lo opuesto de caro? ____________________ 6. \u00bfDe qu\u00e9 color es la nieve? ____________________ 7. \u00bfDe qu\u00e9 color son los autobuses de la escuela? ____________________ 8. \u00bfDe qu\u00e9 color es la hierba (?grass?)? ____________________ 9. \u00bfDe qu\u00e9 color es el caf\u00e9 (?coffee?)? ____________________ 10. \u00bfDe qu\u00e9 colores es la bandera (?flag?) de EE.UU.? ____________________<\/p>\n<p>INDIRECT OBJECTS: ?Use the cues in parentheses to provide the correct ?indirect object pronoun for each sentence. (5 pts.) 1. La dependienta ____________________ vendi\u00f3 la corbata. (a Uds.) 2. Sus amigos ____________________ prestaron el dinero. (a ellos) 3. Sergio y Enrique ____________________ compraron una corbata. (a ti) 4. Nosotros ____________________ escribimos una carta. (a ella) 5. El vendedor ____________________ describi\u00f3 el nuevo centro comercial. (a nosotros) Fill in the missing pronoun (5) 1. She asked ?me? for the book Ella__________pidi\u00f3 el libro 2. Did you tell ?her? the truth? ?_______dijiste la verdad?<\/p>\n<p>3. they gave ?us? three books<\/p>\n<p>Ellos_______dieron tres libros<\/p>\n<p>4. We spoke ?to you? yesterday<\/p>\n<p>Nosotros_______hablamos ayer<\/p>\n<p>5. I gave ?them? the directions<\/p>\n<p>Yo_________di las direcciones. \u00bf?CUANTOS?? Write the following numbers in Spanish (5)<\/p>\n<p>1. Elena naci\u00f3 en ?1987 2. Hay? 569? p\u00e1ginas 3. 952? personas<\/p>\n<p><center><a href=\"http:\/\/onlineclassesguru.com\/orders\/ordernow\"><img decoding=\"async\" src=\"https:\/\/encrypted-tbn0.gstatic.com\/images?q=tbn:ANd9GcTyj99p60XCLyLk1htB7-1neRt8-2QdnenNlQ&usqp=CAU\"target=\"_http:\/\/onlineclassesguru.com\/orders\/ordernow\"\/><\/center><p>","protected":false},"excerpt":{"rendered":"<p>VOCABULARIO? Write the letter of the sentence in column B that is most logically related to each question or statement in column A. (10 pts.) A 1. __________ \u00bfD\u00f3nde est\u00e1 la tienda? 2. __________ \u00bfQu\u00e9 talla usa Ud.? 3. __________ La tienda est\u00e1 de rebajas. 4. __________ Tengo fr\u00edo en las manos. 5. __________ Voy&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3972","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>VOCABULARIO - onlineclassesguru<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VOCABULARIO - onlineclassesguru\" \/>\n<meta property=\"og:description\" content=\"VOCABULARIO? Write the letter of the sentence in column B that is most logically related to each question or statement in column A. (10 pts.) A 1. __________ \u00bfD\u00f3nde est\u00e1 la tienda? 2. __________ \u00bfQu\u00e9 talla usa Ud.? 3. __________ La tienda est\u00e1 de rebajas. 4. __________ Tengo fr\u00edo en las manos. 5. __________ Voy...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/\" \/>\n<meta property=\"og:site_name\" content=\"onlineclassesguru\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-11T08:34:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/onlineclassesguru.com\/#website\",\"url\":\"https:\/\/onlineclassesguru.com\/\",\"name\":\"onlineclassesguru\",\"description\":\"Cheap Professional coursework and reaction papers help\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/onlineclassesguru.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/#webpage\",\"url\":\"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/\",\"name\":\"VOCABULARIO - onlineclassesguru\",\"isPartOf\":{\"@id\":\"https:\/\/onlineclassesguru.com\/#website\"},\"datePublished\":\"2020-11-11T08:34:56+00:00\",\"dateModified\":\"2020-11-11T08:34:56+00:00\",\"author\":{\"@id\":\"https:\/\/onlineclassesguru.com\/#\/schema\/person\/1831fa4d28e47b468621cf27932f5742\"},\"breadcrumb\":{\"@id\":\"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/onlineclassesguru.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VOCABULARIO\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/onlineclassesguru.com\/#\/schema\/person\/1831fa4d28e47b468621cf27932f5742\",\"name\":\"admin_admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/onlineclassesguru.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/429c8d043f7a770af242b0031e8b9f2b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/429c8d043f7a770af242b0031e8b9f2b?s=96&d=mm&r=g\",\"caption\":\"admin_admin\"},\"url\":\"https:\/\/onlineclassesguru.com\/index.php\/author\/admin_admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VOCABULARIO - onlineclassesguru","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/","og_locale":"en_US","og_type":"article","og_title":"VOCABULARIO - onlineclassesguru","og_description":"VOCABULARIO? Write the letter of the sentence in column B that is most logically related to each question or statement in column A. (10 pts.) A 1. __________ \u00bfD\u00f3nde est\u00e1 la tienda? 2. __________ \u00bfQu\u00e9 talla usa Ud.? 3. __________ La tienda est\u00e1 de rebajas. 4. __________ Tengo fr\u00edo en las manos. 5. __________ Voy...","og_url":"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/","og_site_name":"onlineclassesguru","article_published_time":"2020-11-11T08:34:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin_admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/onlineclassesguru.com\/#website","url":"https:\/\/onlineclassesguru.com\/","name":"onlineclassesguru","description":"Cheap Professional coursework and reaction papers help","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onlineclassesguru.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/#webpage","url":"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/","name":"VOCABULARIO - onlineclassesguru","isPartOf":{"@id":"https:\/\/onlineclassesguru.com\/#website"},"datePublished":"2020-11-11T08:34:56+00:00","dateModified":"2020-11-11T08:34:56+00:00","author":{"@id":"https:\/\/onlineclassesguru.com\/#\/schema\/person\/1831fa4d28e47b468621cf27932f5742"},"breadcrumb":{"@id":"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/onlineclassesguru.com\/index.php\/2020\/11\/11\/vocabulario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/onlineclassesguru.com\/"},{"@type":"ListItem","position":2,"name":"VOCABULARIO"}]},{"@type":"Person","@id":"https:\/\/onlineclassesguru.com\/#\/schema\/person\/1831fa4d28e47b468621cf27932f5742","name":"admin_admin","image":{"@type":"ImageObject","@id":"https:\/\/onlineclassesguru.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/429c8d043f7a770af242b0031e8b9f2b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/429c8d043f7a770af242b0031e8b9f2b?s=96&d=mm&r=g","caption":"admin_admin"},"url":"https:\/\/onlineclassesguru.com\/index.php\/author\/admin_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/posts\/3972"}],"collection":[{"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/comments?post=3972"}],"version-history":[{"count":1,"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/posts\/3972\/revisions"}],"predecessor-version":[{"id":3973,"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/posts\/3972\/revisions\/3973"}],"wp:attachment":[{"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/media?parent=3972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/categories?post=3972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlineclassesguru.com\/index.php\/wp-json\/wp\/v2\/tags?post=3972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}